{"id":11887,"date":"2024-06-13T14:19:51","date_gmt":"2024-06-13T13:19:51","guid":{"rendered":"https:\/\/eranovum.energy\/?p=11887"},"modified":"2024-06-13T12:57:00","modified_gmt":"2024-06-13T12:57:00","slug":"temps-recharge-voiture-electrique","status":"publish","type":"post","link":"https:\/\/eranovum.energy\/fr\/blog\/temps-recharge-voiture-electrique\/","title":{"rendered":"Quel est le temps de recharge d\u2019une voiture \u00e9lectrique ?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"11887\" class=\"elementor elementor-11887\">\n\t\t\t\t<div class=\"elementor-element elementor-element-030130a e-flex e-con-boxed sc_layouts_column_icons_position_left e-con e-parent\" data-id=\"030130a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3a6548a e-con-full e-flex sc_layouts_column_icons_position_left e-con e-child\" data-id=\"3a6548a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fdf72b8 sc_fly_static elementor-widget elementor-widget-button\" data-id=\"fdf72b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/eranovum.energy\/fr\/blog-fr\/mobilite-durable\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mobilit\u00e9 durable<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9015b91 meta-fecha sc_fly_static elementor-widget elementor-widget-trx_sc_layouts_meta\" data-id=\"9015b91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"trx_sc_layouts_meta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div   class=\"post_meta sc_layouts_meta sc_layouts_meta_default \">\n\t<div class=\"post_meta\"><span class=\"post_meta_item post_date\"><a href=\"https:\/\/eranovum.energy\/fr\/blog\/temps-recharge-voiture-electrique\/\">13\/06\/2024<\/a><\/span><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7735e8 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"b7735e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a2c1329 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"a2c1329\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ae44943 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"ae44943\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-90ec193 sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"90ec193\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">L\u2019une des questions les plus fr\u00e9quemment pos\u00e9es par les personnes qui envisagent d\u2019acheter une <\/span><b>voiture \u00e9lectrique<\/b><span style=\"font-weight: 400;\"> et de privil\u00e9gier <\/span><b>une mobilit\u00e9 plus durable<\/b><span style=\"font-weight: 400;\"> porte sur le temps n\u00e9cessaire pour effectuer une recharge compl\u00e8te.<\/span><\/p><p><span style=\"font-weight: 400;\">En r\u00e9alit\u00e9, il n\u2019existe pas de r\u00e9ponse pr\u00e9cise, de nombre exact d\u2019heures ou de minutes. <\/span><span style=\"font-weight: 400;\">Le <\/span><b>temps de recharge d\u2019une voiture \u00e9lectrique est une donn\u00e9e relative qui, comme nous allons le voir, d\u00e9pend de plusieurs facteurs. <\/b><span style=\"font-weight: 400;\">Conna\u00eetre ces aspects permet de <\/span><b>g\u00e9rer les d\u00e9lais<\/b><span style=\"font-weight: 400;\">, de <\/span><b>faire des choix judicieux <\/b><span style=\"font-weight: 400;\">et d\u2019<\/span><b>\u00e9valuer le meilleur moment<\/b><span style=\"font-weight: 400;\"> pour brancher votre v\u00e9hicule. Nous allons les d\u00e9couvrir ensemble dans cet article !<\/span><\/p><h2><b>Temps de recharge des voitures \u00e9lectriques : de quelques minutes \u00e0 quelques heures<\/b><\/h2><p><span style=\"font-weight: 400;\">Il existe aujourd\u2019hui <\/span><b>plusieurs types de recharges<\/b><span style=\"font-weight: 400;\"> qui se diff\u00e9rencient par le temps de recharge, le type de courant, la puissance et la localisation des infrastructures.<\/span><\/p><ul><li><span style=\"font-weight: 400;\"> \u00a0 <\/span><b>Recharge lente<\/b><span style=\"font-weight: 400;\"> : le <\/span><b>temps de recharge est compris entre 4 et 8 heures.<\/b><span style=\"font-weight: 400;\"> Elle est fr\u00e9quemment utilis\u00e9e au niveau des points domestiques \u00e0 usage priv\u00e9 ainsi que dans certains centres commerciaux et certaines entreprises \u00e0 acc\u00e8s public. Le <\/span><b>courant est alternatif (CA) monophas\u00e9<\/b><span style=\"font-weight: 400;\"> et la puissance varie de <\/span><b>3,7 kW \u00e0 7,4 kW<\/b><span style=\"font-weight: 400;\">.<\/span><\/li><li><b>Recharge semi-rapide<\/b><span style=\"font-weight: 400;\"> : la dur\u00e9e estim\u00e9e de ce type de recharge se situe autour de <\/span><b>3 heures<\/b><span style=\"font-weight: 400;\">, et selon le v\u00e9hicule et le type de courant, monophas\u00e9 ou triphas\u00e9, elle <\/span><b>peut aller jusqu\u2019\u00e0 5 heures<\/b><span style=\"font-weight: 400;\">. La puissance maximale peut atteindre <\/span><b>22 kW<\/b><span style=\"font-weight: 400;\">. Ces points de recharge se situent dans les grands centres commerciaux, les parkings d\u2019entreprises ou les parkings de flottes automobiles, c\u2019est-\u00e0-dire les lieux o\u00f9 le nombre d\u2019utilisateurs de voitures \u00e9lectriques est le plus \u00e9lev\u00e9 et o\u00f9 les v\u00e9hicules restent stationn\u00e9s tout au long de la journ\u00e9e de travail, ou pendant que les conducteurs participent \u00e0 des activit\u00e9s qui n\u00e9cessitent un certain temps, comme le shopping ou les loisirs.<\/span><\/li><li><span style=\"font-weight: 400;\"> \u00a0 <\/span><b>Recharge rapide<\/b><span style=\"font-weight: 400;\"> : elle permet d\u2019atteindre 80 % de la batterie en environ <\/span><b>30 minutes<\/b><span style=\"font-weight: 400;\">, avec une puissance de recharge maximale pouvant atteindre <\/span><b>150 kW<\/b><span style=\"font-weight: 400;\">. Il s\u2019agit g\u00e9n\u00e9ralement de bornes de courant continu triphas\u00e9 situ\u00e9es sur les autoroutes et les voies express.<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">\u25cf<\/span><span style=\"font-weight: 400;\"> \u00a0 \u00a0 <\/span><b>Recharge ultrarapide<\/b><span style=\"font-weight: 400;\"> : ce type de recharge permet de charger une batterie de 20 % \u00e0 80 % en <\/span><b>15 minutes<\/b><span style=\"font-weight: 400;\"> seulement, avec des puissances <\/span><b>\u00e0 partir de 150 kW<\/b><span style=\"font-weight: 400;\">. Cette solution est particuli\u00e8rement utile pour les trajets de moyenne distance.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07a9e3e sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"07a9e3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5965be0 sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"5965be0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><b>Types de recharge des v\u00e9hicules \u00e9lectriques en fonction du temps et de la puissance<\/b><\/h3>\n<table style=\"width: 100%;\">\n<tbody>\n<tr>\n<td style=\"color: #3e3e3e;\"><b>Type de recharge<\/b><\/td>\n<td style=\"color: #3e3e3e;\"><b>Temps de recharge<\/b><\/td>\n<td style=\"color: #3e3e3e;\"><b>Puissance<\/b><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400; color: #3e3e3e;\">Lente<\/span><\/td>\n<td><span style=\"font-weight: 400; color: #3e3e3e;\">4 \u00e0 8 heures<\/span><\/td>\n<td><span style=\"font-weight: 400; color: #3e3e3e;\">3,7-7,4 kW<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400; color: #3e3e3e;\">Semi-rapide<\/span><\/td>\n<td><span style=\"font-weight: 400; color: #3e3e3e;\">3 \u00e0 5 heures<\/span><\/td>\n<td><span style=\"font-weight: 400; color: #3e3e3e;\">22 kW<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400; color: #3e3e3e;\">Rapide<\/span><\/td>\n<td><span style=\"font-weight: 400; color: #3e3e3e;\">30 minutes<\/span><\/td>\n<td><span style=\"font-weight: 400; color: #3e3e3e;\">De 60 \u00e0 150 kW<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400; color: #3e3e3e;\">Ultrarapide<\/span><\/td>\n<td><span style=\"font-weight: 400; color: #3e3e3e;\">15 minutes<\/span><\/td>\n<td><span style=\"font-weight: 400; color: #3e3e3e;\">\u00c0 partir de 150 kW<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ac9950 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"5ac9950\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d1d6307 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"d1d6307\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7a903b9 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"7a903b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7cd71de sc_fly_static elementor-widget elementor-widget-image\" data-id=\"7cd71de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1831\" height=\"765\" src=\"https:\/\/eranovum.energy\/wp-content\/uploads\/2024\/06\/temps-recharge-voiture-electrique.jpg\" class=\"attachment-full size-full wp-image-11889\" alt=\"Diff\u00e9rents types de recharge en fonction du temps n\u00e9cessaire \u00e0 la recharge et de la puissance du chargeur.\" srcset=\"https:\/\/eranovum.energy\/wp-content\/uploads\/2024\/06\/temps-recharge-voiture-electrique.jpg 1831w, https:\/\/eranovum.energy\/wp-content\/uploads\/2024\/06\/temps-recharge-voiture-electrique-300x125.jpg 300w, https:\/\/eranovum.energy\/wp-content\/uploads\/2024\/06\/temps-recharge-voiture-electrique-1024x428.jpg 1024w, https:\/\/eranovum.energy\/wp-content\/uploads\/2024\/06\/temps-recharge-voiture-electrique-768x321.jpg 768w, https:\/\/eranovum.energy\/wp-content\/uploads\/2024\/06\/temps-recharge-voiture-electrique-1536x642.jpg 1536w, https:\/\/eranovum.energy\/wp-content\/uploads\/2024\/06\/temps-recharge-voiture-electrique-370x155.jpg 370w, https:\/\/eranovum.energy\/wp-content\/uploads\/2024\/06\/temps-recharge-voiture-electrique-840x351.jpg 840w, https:\/\/eranovum.energy\/wp-content\/uploads\/2024\/06\/temps-recharge-voiture-electrique-410x171.jpg 410w\" sizes=\"(max-width: 1831px) 100vw, 1831px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2089c83 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"2089c83\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4b3efbc sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"4b3efbc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fdc8b3d sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"fdc8b3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-995e0e6 sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"995e0e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><b>Quels sont les facteurs qui influencent le temps de recharge d\u2019une voiture \u00e9lectrique ?<\/b><\/h2><p><span style=\"font-weight: 400;\">Toutes les <\/span><b>voitures \u00e9lectriques<\/b><span style=\"font-weight: 400;\"> ne poss\u00e8dent pas les m\u00eames besoins, et tous les <\/span><b>points de recharge pour v\u00e9hicules \u00e9lectriques<\/b><span style=\"font-weight: 400;\"> ne sont pas identiques. Examinons ensemble les facteurs qui d\u00e9terminent le temps d\u2019alimentation des v\u00e9hicules \u00e9lectriques.<\/span><\/p><h3><b>1.\u00a0 \u00a0 Caract\u00e9ristiques du mod\u00e8le de voiture \u00e9lectrique<\/b><\/h3><p><span style=\"font-weight: 400;\">Aussi rapide que nous souhaitions que soit le processus, le mod\u00e8le de la voiture \u00e9lectrique et ses caract\u00e9ristiques doivent \u00eatre pris en compte. Dans certains cas, la <\/span><b>vitesse de charge de la voiture peut \u00eatre limit\u00e9e par le constructeur<\/b><span style=\"font-weight: 400;\">. Le fabricant indique g\u00e9n\u00e9ralement la <\/span><b>vitesse de charge maximale<\/b><span style=\"font-weight: 400;\">, mais dans la pratique, il s\u2019agit d\u2019une courbe qui peut \u00e9voluer \u00e0 mesure que le <\/span><b>pourcentage de charge du v\u00e9hicule <\/b><span style=\"font-weight: 400;\">augmente. Par exemple, certaines voitures pr\u00e9sentent une <\/span><b>puissance de charge maximale de 150 kW<\/b><span style=\"font-weight: 400;\">, avec une <\/span><b>moyenne de 100 kW<\/b><span style=\"font-weight: 400;\">. Dans d\u2019autres cas, certains v\u00e9hicules n\u2019atteignent qu\u2019une <\/span><b>moyenne de 60 kW<\/b><span style=\"font-weight: 400;\">, ce qui peut prolonger le temps de recharge<\/span><b> jusqu\u2019\u00e0 10 minutes<\/b><span style=\"font-weight: 400;\"> pour atteindre une recharge compl\u00e8te.<\/span><\/p><h3><b>2.\u00a0 \u00a0 Batteries, dimensions, capacit\u00e9 et puissance<\/b><\/h3><p><span style=\"font-weight: 400;\">La <\/span><b>capacit\u00e9 de la batterie<\/b><span style=\"font-weight: 400;\"> d\u2019une voiture \u00e9lectrique a un impact sur le temps de recharge : plus la batterie a une grande capacit\u00e9, plus il faut de temps pour atteindre une recharge \u00e0 100 %.<\/span><\/p><p><span style=\"font-weight: 400;\">La <\/span><b>capacit\u00e9 d\u2019une batterie<\/b><span style=\"font-weight: 400;\"> est mesur\u00e9e en kilowattheures (kWh) et est comparable au volume du r\u00e9servoir de carburant des v\u00e9hicules \u00e0 moteur \u00e0 combustion. En g\u00e9n\u00e9ral, la capacit\u00e9 des <\/span><b>batteries de v\u00e9hicules \u00e9lectriques<\/b><span style=\"font-weight: 400;\"> se diff\u00e9rencie par :<\/span><\/p><ul><li><span style=\"font-weight: 400;\">Hybrides rechargeables : 12 kWh.<\/span><\/li><li><span style=\"font-weight: 400;\">Utilitaires 100 % \u00e9lectriques : 50 kWh. Avec une autonomie comprise entre 200 et 300 km.<\/span><\/li><li><span style=\"font-weight: 400;\">Voitures 100 % \u00e9lectriques haut de gamme : 80 kWh ou plus. Certains mod\u00e8les de ces v\u00e9hicules peuvent atteindre une autonomie de 900 km.<\/span><\/li><\/ul><h3><span style=\"font-weight: 400;\">La <\/span><b>puissance<\/b><span style=\"font-weight: 400;\"> correspond \u00e0 l\u2019amp\u00e9rage maximal atteint lors du <\/span><b>processus de d\u00e9charge<\/b><span style=\"font-weight: 400;\">. Cela signifie que <\/span><b>plus la puissance est \u00e9lev\u00e9e, meilleures sont les performances de la batterie<\/b><span style=\"font-weight: 400;\">.<\/span><\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c61d667 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"c61d667\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-325c42f elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"325c42f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b405dde sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"b405dde\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-708d9de sc_fly_static elementor-widget elementor-widget-image\" data-id=\"708d9de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1831\" height=\"871\" src=\"https:\/\/eranovum.energy\/wp-content\/uploads\/2024\/06\/chargeurs-voiture-electrique.jpg\" class=\"attachment-full size-full wp-image-11892\" alt=\"Diff\u00e9rents types de recharge en fonction du temps n\u00e9cessaire \u00e0 la recharge et de la puissance du chargeur.\" srcset=\"https:\/\/eranovum.energy\/wp-content\/uploads\/2024\/06\/chargeurs-voiture-electrique.jpg 1831w, https:\/\/eranovum.energy\/wp-content\/uploads\/2024\/06\/chargeurs-voiture-electrique-300x143.jpg 300w, https:\/\/eranovum.energy\/wp-content\/uploads\/2024\/06\/chargeurs-voiture-electrique-1024x487.jpg 1024w, https:\/\/eranovum.energy\/wp-content\/uploads\/2024\/06\/chargeurs-voiture-electrique-768x365.jpg 768w, https:\/\/eranovum.energy\/wp-content\/uploads\/2024\/06\/chargeurs-voiture-electrique-1536x731.jpg 1536w, https:\/\/eranovum.energy\/wp-content\/uploads\/2024\/06\/chargeurs-voiture-electrique-370x176.jpg 370w, https:\/\/eranovum.energy\/wp-content\/uploads\/2024\/06\/chargeurs-voiture-electrique-840x400.jpg 840w, https:\/\/eranovum.energy\/wp-content\/uploads\/2024\/06\/chargeurs-voiture-electrique-410x195.jpg 410w\" sizes=\"(max-width: 1831px) 100vw, 1831px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d9d6a6 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"5d9d6a6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-491a730 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"491a730\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ecdb07 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"2ecdb07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77ede30 sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"77ede30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><b>3.\u00a0 \u00a0 \u00c9tat de charge initial<\/b><\/h3><p><span style=\"font-weight: 400;\">Recharger le v\u00e9hicule lorsqu\u2019il <\/span><b>reste 20 % de batterie<\/b><span style=\"font-weight: 400;\"> prendra moins de temps que de <\/span><b>le recharger lorsque la batterie est presque vide<\/b><span style=\"font-weight: 400;\">.<\/span><\/p><h3><b>4.<\/b> <b>Temp\u00e9ratures pendant la recharge<\/b><\/h3><p><span style=\"font-weight: 400;\">Le <\/span><b>temps de recharge de la batterie<\/b><span style=\"font-weight: 400;\"> varie \u00e9galement en fonction des conditions m\u00e9t\u00e9orologiques : il sera plus long lorsque les temp\u00e9ratures sont extr\u00eames, soit trop froides, soit trop chaudes. Par ailleurs, l\u2019<\/span><b>autonomie de la voiture<\/b><span style=\"font-weight: 400;\"> est \u00e9galement impact\u00e9e par des conditions m\u00e9t\u00e9orologiques exceptionnelles. Comme pour les temps de recharge, l\u2019autonomie est r\u00e9duite lorsque la temp\u00e9rature est basse ou trop \u00e9lev\u00e9e.<\/span><span style=\"font-weight: 400;\"><br \/><\/span><\/p><h2><b>R\u00e9seau de bornes de recharge \u00e0 \u00e9nergie renouvelable d\u2019Eranovum<\/b><\/h2><p><span style=\"font-weight: 400;\">Chez Eranovum, nous proposons des <\/span><b>solutions de recharge dans des gammes de puissance allant de 22 kW \u00e0 150 kW<\/b><span style=\"font-weight: 400;\">. Nous nous adaptons \u00e0 chaque lieu, c\u2019est la raison pour laquelle nos stations de recharge combinent un ensemble de chargeurs incluant des <\/span><b>chargeurs de grande puissance de 150 kW<\/b><span style=\"font-weight: 400;\">, permettant de recharger la batterie d\u2019une voiture \u00e9lectrique en moins de 20 minutes, tout en proposant des <\/span><b>solutions de recharge dans toutes les gammes de puissance<\/b><span style=\"font-weight: 400;\">, y compris avec des mod\u00e8les combinant des chargeurs de <\/span><b>puissance mixte<\/b><span style=\"font-weight: 400;\">.<\/span><\/p><p><span style=\"font-weight: 400;\">Le<\/span><strong><a href=\"https:\/\/eranovum.energy\/fr\/notre-reseau\/\" target=\"_blank\" rel=\"noopener\"> r\u00e9seau de bornes de recharge pour v\u00e9hicules \u00e9lectriques d\u2019Eranovum<\/a><\/strong><span style=\"font-weight: 400;\"> ne cesse de se d\u00e9velopper. Dans chacun de ces points, nous <\/span><b>fournissons de l\u2019\u00e9nergie propre et 100% renouvelable<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c4d35e sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"5c4d35e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-61f6539 e-con-full e-flex sc_layouts_column_icons_position_left e-con e-parent\" data-id=\"61f6539\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div data-animation-type=\"block\" class=\"elementor-element elementor-element-3fd8638 animated-slow e-flex e-con-boxed sc_layouts_column_icons_position_left animation_type_block elementor-invisible e-con e-child\" data-id=\"3fd8638\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;qwery-fadeinup&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-83ea41b elementor-widget__width-initial elementor-widget-mobile__width-initial sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"83ea41b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>T\u00e9l\u00e9chargez l\u2019application Eranovum<\/b><span style=\"font-weight: 400;\"> et localisez les bornes de recharge les plus proches de chez vous.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-animation-type=\"block\" class=\"elementor-element elementor-element-f7ffc89 animated-slow animation_type_block sc_fly_static elementor-invisible elementor-widget elementor-widget-button\" data-id=\"f7ffc89\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;qwery-fadeinup&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/eranovum.energy\/fr\/notre-reseau\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Notre r\u00e9seau<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-accfa90 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"accfa90\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f43ed30 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"f43ed30\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4493cc3 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"4493cc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0c9982 sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"a0c9982\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Si vous poss\u00e9dez un b\u00e2timent avec parking et que vous souhaitez installer des bornes de recharge,<\/span><strong><a href=\"https:\/\/eranovum.energy\/fr\/contact-2\/\" target=\"_blank\" rel=\"noopener\"> contactez Eranovum<\/a><\/strong><span style=\"font-weight: 400;\"><strong>,<\/strong> votre partenaire en \u00e9nergie durable de nouvelle g\u00e9n\u00e9ration !<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e38577 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"5e38577\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Mobilit\u00e9 durable 13\/06\/2024 L\u2019une des questions les plus fr\u00e9quemment pos\u00e9es par les personnes qui envisagent&hellip;<\/p>\n","protected":false},"author":1,"featured_media":11899,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","_acf_changed":false,"footnotes":""},"categories":[266,302],"tags":[],"class_list":["post-11887","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-mobilite-durable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le temps de recharge d\u2019une voiture \u00e9lectrique | Blog Eranovum<\/title>\n<meta name=\"description\" content=\"Conna\u00eetre le temps de recharge d\u2019une voiture \u00e9lectrique permet de savoir quand, comment et o\u00f9 la brancher. D\u00e9couvrez-en plus sur le blog d\u2019Eranovum.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eranovum.energy\/fr\/blog\/temps-recharge-voiture-electrique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le temps de recharge d\u2019une voiture \u00e9lectrique | Blog Eranovum\" \/>\n<meta property=\"og:description\" content=\"Conna\u00eetre le temps de recharge d\u2019une voiture \u00e9lectrique permet de savoir quand, comment et o\u00f9 la brancher. D\u00e9couvrez-en plus sur le blog d\u2019Eranovum.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eranovum.energy\/fr\/blog\/temps-recharge-voiture-electrique\/\" \/>\n<meta property=\"og:site_name\" content=\"Eranovum\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-13T13:19:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eranovum.energy\/wp-content\/uploads\/2024\/06\/temps-recharge-voiture-electrique-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"quadrosphera\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"quadrosphera\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eranovum.energy\\\/fr\\\/blog\\\/temps-recharge-voiture-electrique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eranovum.energy\\\/fr\\\/blog\\\/temps-recharge-voiture-electrique\\\/\"},\"author\":{\"name\":\"quadrosphera\",\"@id\":\"https:\\\/\\\/eranovum.energy\\\/fr\\\/#\\\/schema\\\/person\\\/8899ee21829052240fb60fc9ce870a50\"},\"headline\":\"Quel est le temps de recharge d\u2019une voiture \u00e9lectrique ?\",\"datePublished\":\"2024-06-13T13:19:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eranovum.energy\\\/fr\\\/blog\\\/temps-recharge-voiture-electrique\\\/\"},\"wordCount\":1061,\"publisher\":{\"@id\":\"https:\\\/\\\/eranovum.energy\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eranovum.energy\\\/fr\\\/blog\\\/temps-recharge-voiture-electrique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eranovum.energy\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/temps-recharge-voiture-electrique-1.jpg\",\"articleSection\":[\"Blog\",\"Mobilit\u00e9 durable\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eranovum.energy\\\/fr\\\/blog\\\/temps-recharge-voiture-electrique\\\/\",\"url\":\"https:\\\/\\\/eranovum.energy\\\/fr\\\/blog\\\/temps-recharge-voiture-electrique\\\/\",\"name\":\"Le temps de recharge d\u2019une voiture \u00e9lectrique | Blog Eranovum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eranovum.energy\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eranovum.energy\\\/fr\\\/blog\\\/temps-recharge-voiture-electrique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eranovum.energy\\\/fr\\\/blog\\\/temps-recharge-voiture-electrique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eranovum.energy\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/temps-recharge-voiture-electrique-1.jpg\",\"datePublished\":\"2024-06-13T13:19:51+00:00\",\"description\":\"Conna\u00eetre le temps de recharge d\u2019une voiture \u00e9lectrique permet de savoir quand, comment et o\u00f9 la brancher. D\u00e9couvrez-en plus sur le blog d\u2019Eranovum.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eranovum.energy\\\/fr\\\/blog\\\/temps-recharge-voiture-electrique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eranovum.energy\\\/fr\\\/blog\\\/temps-recharge-voiture-electrique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/eranovum.energy\\\/fr\\\/blog\\\/temps-recharge-voiture-electrique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eranovum.energy\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/temps-recharge-voiture-electrique-1.jpg\",\"contentUrl\":\"https:\\\/\\\/eranovum.energy\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/temps-recharge-voiture-electrique-1.jpg\",\"width\":1500,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eranovum.energy\\\/fr\\\/blog\\\/temps-recharge-voiture-electrique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eranovum.energy\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quel est le temps de recharge d\u2019une voiture \u00e9lectrique ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eranovum.energy\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/eranovum.energy\\\/fr\\\/\",\"name\":\"Eranovum\",\"description\":\"Leading the new era of energy\",\"publisher\":{\"@id\":\"https:\\\/\\\/eranovum.energy\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eranovum.energy\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eranovum.energy\\\/fr\\\/#organization\",\"name\":\"Eranovum\",\"url\":\"https:\\\/\\\/eranovum.energy\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/eranovum.energy\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eranovum.energy\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/cropped-eranovum-logo-web.png\",\"contentUrl\":\"https:\\\/\\\/eranovum.energy\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/cropped-eranovum-logo-web.png\",\"width\":351,\"height\":41,\"caption\":\"Eranovum\"},\"image\":{\"@id\":\"https:\\\/\\\/eranovum.energy\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eranovum.energy\\\/fr\\\/#\\\/schema\\\/person\\\/8899ee21829052240fb60fc9ce870a50\",\"name\":\"quadrosphera\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bfa148e4674c11710ff73f8c29dc349dc77f5bc8cdcc356e0f0ea4497d2083df?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bfa148e4674c11710ff73f8c29dc349dc77f5bc8cdcc356e0f0ea4497d2083df?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bfa148e4674c11710ff73f8c29dc349dc77f5bc8cdcc356e0f0ea4497d2083df?s=96&d=mm&r=g\",\"caption\":\"quadrosphera\"},\"sameAs\":[\"https:\\\/\\\/eranovum.energy\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le temps de recharge d\u2019une voiture \u00e9lectrique | Blog Eranovum","description":"Conna\u00eetre le temps de recharge d\u2019une voiture \u00e9lectrique permet de savoir quand, comment et o\u00f9 la brancher. D\u00e9couvrez-en plus sur le blog d\u2019Eranovum.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eranovum.energy\/fr\/blog\/temps-recharge-voiture-electrique\/","og_locale":"fr_FR","og_type":"article","og_title":"Le temps de recharge d\u2019une voiture \u00e9lectrique | Blog Eranovum","og_description":"Conna\u00eetre le temps de recharge d\u2019une voiture \u00e9lectrique permet de savoir quand, comment et o\u00f9 la brancher. D\u00e9couvrez-en plus sur le blog d\u2019Eranovum.","og_url":"https:\/\/eranovum.energy\/fr\/blog\/temps-recharge-voiture-electrique\/","og_site_name":"Eranovum","article_published_time":"2024-06-13T13:19:51+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/eranovum.energy\/wp-content\/uploads\/2024\/06\/temps-recharge-voiture-electrique-1.jpg","type":"image\/jpeg"}],"author":"quadrosphera","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"quadrosphera","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eranovum.energy\/fr\/blog\/temps-recharge-voiture-electrique\/#article","isPartOf":{"@id":"https:\/\/eranovum.energy\/fr\/blog\/temps-recharge-voiture-electrique\/"},"author":{"name":"quadrosphera","@id":"https:\/\/eranovum.energy\/fr\/#\/schema\/person\/8899ee21829052240fb60fc9ce870a50"},"headline":"Quel est le temps de recharge d\u2019une voiture \u00e9lectrique ?","datePublished":"2024-06-13T13:19:51+00:00","mainEntityOfPage":{"@id":"https:\/\/eranovum.energy\/fr\/blog\/temps-recharge-voiture-electrique\/"},"wordCount":1061,"publisher":{"@id":"https:\/\/eranovum.energy\/fr\/#organization"},"image":{"@id":"https:\/\/eranovum.energy\/fr\/blog\/temps-recharge-voiture-electrique\/#primaryimage"},"thumbnailUrl":"https:\/\/eranovum.energy\/wp-content\/uploads\/2024\/06\/temps-recharge-voiture-electrique-1.jpg","articleSection":["Blog","Mobilit\u00e9 durable"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/eranovum.energy\/fr\/blog\/temps-recharge-voiture-electrique\/","url":"https:\/\/eranovum.energy\/fr\/blog\/temps-recharge-voiture-electrique\/","name":"Le temps de recharge d\u2019une voiture \u00e9lectrique | Blog Eranovum","isPartOf":{"@id":"https:\/\/eranovum.energy\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eranovum.energy\/fr\/blog\/temps-recharge-voiture-electrique\/#primaryimage"},"image":{"@id":"https:\/\/eranovum.energy\/fr\/blog\/temps-recharge-voiture-electrique\/#primaryimage"},"thumbnailUrl":"https:\/\/eranovum.energy\/wp-content\/uploads\/2024\/06\/temps-recharge-voiture-electrique-1.jpg","datePublished":"2024-06-13T13:19:51+00:00","description":"Conna\u00eetre le temps de recharge d\u2019une voiture \u00e9lectrique permet de savoir quand, comment et o\u00f9 la brancher. D\u00e9couvrez-en plus sur le blog d\u2019Eranovum.","breadcrumb":{"@id":"https:\/\/eranovum.energy\/fr\/blog\/temps-recharge-voiture-electrique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eranovum.energy\/fr\/blog\/temps-recharge-voiture-electrique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/eranovum.energy\/fr\/blog\/temps-recharge-voiture-electrique\/#primaryimage","url":"https:\/\/eranovum.energy\/wp-content\/uploads\/2024\/06\/temps-recharge-voiture-electrique-1.jpg","contentUrl":"https:\/\/eranovum.energy\/wp-content\/uploads\/2024\/06\/temps-recharge-voiture-electrique-1.jpg","width":1500,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/eranovum.energy\/fr\/blog\/temps-recharge-voiture-electrique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eranovum.energy\/fr\/"},{"@type":"ListItem","position":2,"name":"Quel est le temps de recharge d\u2019une voiture \u00e9lectrique ?"}]},{"@type":"WebSite","@id":"https:\/\/eranovum.energy\/fr\/#website","url":"https:\/\/eranovum.energy\/fr\/","name":"Eranovum","description":"Leading the new era of energy","publisher":{"@id":"https:\/\/eranovum.energy\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eranovum.energy\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/eranovum.energy\/fr\/#organization","name":"Eranovum","url":"https:\/\/eranovum.energy\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/eranovum.energy\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/eranovum.energy\/wp-content\/uploads\/2022\/04\/cropped-eranovum-logo-web.png","contentUrl":"https:\/\/eranovum.energy\/wp-content\/uploads\/2022\/04\/cropped-eranovum-logo-web.png","width":351,"height":41,"caption":"Eranovum"},"image":{"@id":"https:\/\/eranovum.energy\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/eranovum.energy\/fr\/#\/schema\/person\/8899ee21829052240fb60fc9ce870a50","name":"quadrosphera","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/bfa148e4674c11710ff73f8c29dc349dc77f5bc8cdcc356e0f0ea4497d2083df?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bfa148e4674c11710ff73f8c29dc349dc77f5bc8cdcc356e0f0ea4497d2083df?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bfa148e4674c11710ff73f8c29dc349dc77f5bc8cdcc356e0f0ea4497d2083df?s=96&d=mm&r=g","caption":"quadrosphera"},"sameAs":["https:\/\/eranovum.energy"]}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/eranovum.energy\/fr\/wp-json\/wp\/v2\/posts\/11887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranovum.energy\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eranovum.energy\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eranovum.energy\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eranovum.energy\/fr\/wp-json\/wp\/v2\/comments?post=11887"}],"version-history":[{"count":0,"href":"https:\/\/eranovum.energy\/fr\/wp-json\/wp\/v2\/posts\/11887\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eranovum.energy\/fr\/wp-json\/wp\/v2\/media\/11899"}],"wp:attachment":[{"href":"https:\/\/eranovum.energy\/fr\/wp-json\/wp\/v2\/media?parent=11887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eranovum.energy\/fr\/wp-json\/wp\/v2\/categories?post=11887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eranovum.energy\/fr\/wp-json\/wp\/v2\/tags?post=11887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}