{"id":2084,"date":"2022-06-15T08:38:56","date_gmt":"2022-06-15T07:38:56","guid":{"rendered":"https:\/\/eranovum.energy\/?p=2084"},"modified":"2022-06-15T18:18:00","modified_gmt":"2022-06-15T18:18:00","slug":"eranovum-obtiene-265-millones-de-euros-del-fondo-internacional-keystone-para-crear-una-de-las-mayores-redes-de-recarga-de-vehiculos-electricos-en-espana","status":"publish","type":"post","link":"https:\/\/eranovum.energy\/es\/sala-de-prensa\/eranovum-obtiene-265-millones-de-euros-del-fondo-internacional-keystone-para-crear-una-de-las-mayores-redes-de-recarga-de-vehiculos-electricos-en-espana\/","title":{"rendered":"Eranovum obtiene 26,5 millones de euros del fondo internacional Keystone para crear una de las mayores redes de recarga de veh\u00edculos el\u00e9ctricos en Espa\u00f1a"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2084\" class=\"elementor elementor-2084\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a2c1329 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"a2c1329\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ae44943 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"ae44943\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-90ec193 sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"90ec193\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Toda la red de Eranovum suministrar\u00e1 energ\u00eda 100% renovable<\/li><li>Hasta la fecha, la red de recarga de Eranovum cuenta con 60 puntos de recarga, que se espera que aumenten hasta 600 en 2023<\/li><li>El objetivo de la empresa es invertir 55 millones de euros en los pr\u00f3ximos cuatro a\u00f1os y alcanzar los 5.500 puntos de recarga en Espa\u00f1a en 2026.<\/li><\/ul><p>15 de junio de 2022 &#8211; Eranovum, grupo espa\u00f1ol dedicado a acelerar la transici\u00f3n energ\u00e9tica, ha recibido una inyecci\u00f3n de capital de 26,5 millones de euros por parte de Keystone, fondo de inversi\u00f3n internacional especializado en el sector de las infraestructuras y la energ\u00eda, para crear una de las mayores redes de recarga de veh\u00edculos el\u00e9ctricos en Espa\u00f1a.<\/p><p>La operaci\u00f3n se realizar\u00e1 en dos tramos, el primero de los cuales ya se ha cerrado por 11,5 millones de euros. Mediante esta operaci\u00f3n, el fondo internacional ha adquirido una participaci\u00f3n del 30% en el capital social de Eranovum e-mobility, la filial de movilidad el\u00e9ctrica del Grupo Eranovum. La segunda parte de la inversi\u00f3n est\u00e1 prevista para finales de 2023 y aumentar\u00e1 la participaci\u00f3n de Keystone en la filial hasta el 49%, con una inyecci\u00f3n de 15 millones de euros adicionales, lo que elevar\u00e1 la inversi\u00f3n total a 26,5 millones de euros.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3aaef28 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"3aaef28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b622b6d elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"b622b6d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-02632b2 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"02632b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38a8f3f sc_fly_static elementor-widget elementor-widget-image\" data-id=\"38a8f3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/eranovum.energy\/wp-content\/uploads\/2022\/09\/keystone-eranovum.jpeg\" class=\"attachment-full size-full wp-image-2079\" alt=\"\" srcset=\"https:\/\/eranovum.energy\/wp-content\/uploads\/2022\/09\/keystone-eranovum.jpeg 1200w, https:\/\/eranovum.energy\/wp-content\/uploads\/2022\/09\/keystone-eranovum-300x158.jpeg 300w, https:\/\/eranovum.energy\/wp-content\/uploads\/2022\/09\/keystone-eranovum-1024x538.jpeg 1024w, https:\/\/eranovum.energy\/wp-content\/uploads\/2022\/09\/keystone-eranovum-768x403.jpeg 768w, https:\/\/eranovum.energy\/wp-content\/uploads\/2022\/09\/keystone-eranovum-370x194.jpeg 370w, https:\/\/eranovum.energy\/wp-content\/uploads\/2022\/09\/keystone-eranovum-840x441.jpeg 840w, https:\/\/eranovum.energy\/wp-content\/uploads\/2022\/09\/keystone-eranovum-410x215.jpeg 410w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c55a986 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"c55a986\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-15417be sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"15417be\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6eb7a6 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"e6eb7a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c906cc6 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"c906cc6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6bfd573 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"6bfd573\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-689bd39 sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"689bd39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em>\u00abLa alianza estrat\u00e9gica con Keystone servir\u00e1 para impulsar el negocio de la movilidad sostenible de Eranovum en un momento de especial agitaci\u00f3n en el sector debido a los recientes cambios normativos y al apoyo de la financiaci\u00f3n europea. El despegue del mercado del veh\u00edculo el\u00e9ctrico se enfrenta a importantes barreras que pretendemos eliminar, como la insuficiente disponibilidad de infraestructuras de recarga de acceso p\u00fablico. Aprovechando las sinergias con nuestro negocio de renovables, nuestro objetivo es alcanzar 5.500 puntos de recarga que suministren energ\u00eda 100% renovable en los pr\u00f3ximos cinco a\u00f1os, instalando nuestros cargadores en lugares estrat\u00e9gicos de alta rotaci\u00f3n como centros comerciales, clubes deportivos o supermercados\u00bb<\/em>, afirma <strong>David Vallesp\u00edn, director general de Eranovum e-mobility.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-998a13a elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"998a13a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-97c5c0f sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"97c5c0f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-615c22d sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"615c22d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ff5dac0 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"ff5dac0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-49bb2ac sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"49bb2ac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1392ccf sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"1392ccf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Eranovum fue fundada en 2019 por Jos\u00e9 Luis Aguirre y Guy Shahar Yames, dos empresarios con amplia experiencia en el sector de las energ\u00edas renovables, y con la visi\u00f3n de crear y operar infraestructuras energ\u00e9ticas sostenibles para acelerar la transici\u00f3n energ\u00e9tica. Desde entonces, la empresa ha adquirido, desarrollado y construido proyectos de energ\u00edas renovables en Espa\u00f1a y Grecia en asociaci\u00f3n con fondos internacionales que han canalizado m\u00e1s de 450 millones de euros de inversi\u00f3n.<\/p><p>La cartera de proyectos renovables de Eranovum tiene una capacidad total de 565MW y producir\u00e1 energ\u00eda suficiente para abastecer el equivalente a 350.000 hogares. Los primeros 324MW ya est\u00e1n construidos, y se espera que otros 83MW finalicen su construcci\u00f3n a principios de 2023. El objetivo del grupo es aumentar su cartera de proyectos renovables hasta 1,2GW para 2025.<\/p><p>Adem\u00e1s, a principios de 2021, Eranovum entr\u00f3 en el negocio de la movilidad sostenible con el objetivo de reducir dr\u00e1sticamente su impacto medioambiental y contribuir a una mayor y m\u00e1s r\u00e1pida penetraci\u00f3n del veh\u00edculo el\u00e9ctrico en Espa\u00f1a. Gracias a su capacidad de generaci\u00f3n solar fotovoltaica y a su amplio conocimiento del sector, Eranovum garantiza que toda la electricidad suministrada por sus cargadores es producida al 100% por fuentes renovables.<\/p><p>\u00a0<\/p><p><strong>Una red de puntos de recarga de veh\u00edculos el\u00e9ctricos l\u00edder en Espa\u00f1a<\/strong><\/p><p>Actualmente, la red de Eranovum cuenta con 60 puntos de recarga, que se ampliar\u00e1n hasta 600 en los pr\u00f3ximos 18 meses. Dentro de los planes estrat\u00e9gicos de la compa\u00f1\u00eda, Eranovum pretende alcanzar los 5.500 puntos de recarga en 2026, para lo que tiene previsto invertir 55 millones de euros. Los cargadores de Eranovum tienen potencias que van desde los 22kW hasta los 240kW. Esto demuestra el objetivo de la empresa de instalar y operar cargadores de alta potencia en lugares estrat\u00e9gicos. Estos espacios se ubicar\u00e1n en lugares donde los consumidores puedan recargar sus veh\u00edculos mientras realizan sus actividades diarias, como el trabajo, las compras o la pr\u00e1ctica de deportes. Por ello, los lugares de mayor inter\u00e9s son las zonas urbanas con alta rotaci\u00f3n de personas, como centros comerciales, clubes deportivos, restaurantes y supermercados, entre otros.<\/p><p>Por este motivo, la empresa est\u00e1 en plena expansi\u00f3n, seleccionando los socios adecuados del sector inmobiliario con las mejores ubicaciones para desarrollar su red de recarga. En la actualidad, este sector en Espa\u00f1a est\u00e1 apoyado por la reciente aprobaci\u00f3n de una nueva normativa que obliga a los propietarios de aparcamientos a instalar un punto de recarga por cada 40 plazas.<\/p><p>La propuesta de valor de Eranovum se basa en hacerse cargo de todo el proceso de dise\u00f1o, instalaci\u00f3n y operaci\u00f3n de los cargadores. Al colaborar con sus socios, Eranovum financia toda la inversi\u00f3n en la instalaci\u00f3n y explota los equipos durante a\u00f1os.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Toda la red de Eranovum suministrar\u00e1 energ\u00eda 100% renovable Hasta la fecha, la red de&hellip;<\/p>\n","protected":false},"author":1,"featured_media":2077,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_stopmodifiedupdate":false,"_modified_date":"","_acf_changed":false,"footnotes":""},"categories":[225],"tags":[235,253,301],"class_list":["post-2084","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sala-de-prensa","tag-e-mobility-es","tag-vehiculos-electricos","tag-ev-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eranovum obtiene 26,5 millones de euros del fondo internacional Keystone para crear una de las mayores redes de recarga de veh\u00edculos el\u00e9ctricos en Espa\u00f1a - Eranovum<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eranovum.energy\/es\/sala-de-prensa\/eranovum-obtiene-265-millones-de-euros-del-fondo-internacional-keystone-para-crear-una-de-las-mayores-redes-de-recarga-de-vehiculos-electricos-en-espana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eranovum obtiene 26,5 millones de euros del fondo internacional Keystone para crear una de las mayores redes de recarga de veh\u00edculos el\u00e9ctricos en Espa\u00f1a - Eranovum\" \/>\n<meta property=\"og:description\" content=\"Toda la red de Eranovum suministrar\u00e1 energ\u00eda 100% renovable Hasta la fecha, la red de&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eranovum.energy\/es\/sala-de-prensa\/eranovum-obtiene-265-millones-de-euros-del-fondo-internacional-keystone-para-crear-una-de-las-mayores-redes-de-recarga-de-vehiculos-electricos-en-espana\/\" \/>\n<meta property=\"og:site_name\" content=\"Eranovum\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-15T07:38:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-15T18:18:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eranovum.energy\/wp-content\/uploads\/2022\/09\/eranovum-ev-charge.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2372\" \/>\n\t<meta property=\"og:image:height\" content=\"1578\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"quadrosphera\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"quadrosphera\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eranovum.energy\\\/es\\\/sala-de-prensa\\\/eranovum-obtiene-265-millones-de-euros-del-fondo-internacional-keystone-para-crear-una-de-las-mayores-redes-de-recarga-de-vehiculos-electricos-en-espana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eranovum.energy\\\/es\\\/sala-de-prensa\\\/eranovum-obtiene-265-millones-de-euros-del-fondo-internacional-keystone-para-crear-una-de-las-mayores-redes-de-recarga-de-vehiculos-electricos-en-espana\\\/\"},\"author\":{\"name\":\"quadrosphera\",\"@id\":\"https:\\\/\\\/eranovum.energy\\\/es\\\/#\\\/schema\\\/person\\\/8899ee21829052240fb60fc9ce870a50\"},\"headline\":\"Eranovum obtiene 26,5 millones de euros del fondo internacional Keystone para crear una de las mayores redes de recarga de veh\u00edculos el\u00e9ctricos en Espa\u00f1a\",\"datePublished\":\"2022-06-15T07:38:56+00:00\",\"dateModified\":\"2022-06-15T18:18:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eranovum.energy\\\/es\\\/sala-de-prensa\\\/eranovum-obtiene-265-millones-de-euros-del-fondo-internacional-keystone-para-crear-una-de-las-mayores-redes-de-recarga-de-vehiculos-electricos-en-espana\\\/\"},\"wordCount\":846,\"publisher\":{\"@id\":\"https:\\\/\\\/eranovum.energy\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eranovum.energy\\\/es\\\/sala-de-prensa\\\/eranovum-obtiene-265-millones-de-euros-del-fondo-internacional-keystone-para-crear-una-de-las-mayores-redes-de-recarga-de-vehiculos-electricos-en-espana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eranovum.energy\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/eranovum-ev-charge.jpg\",\"keywords\":[\"E-mobility\",\"Veh\u00edculos el\u00e9ctricos\",\"Ev\"],\"articleSection\":[\"Sala de Prensa\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eranovum.energy\\\/es\\\/sala-de-prensa\\\/eranovum-obtiene-265-millones-de-euros-del-fondo-internacional-keystone-para-crear-una-de-las-mayores-redes-de-recarga-de-vehiculos-electricos-en-espana\\\/\",\"url\":\"https:\\\/\\\/eranovum.energy\\\/es\\\/sala-de-prensa\\\/eranovum-obtiene-265-millones-de-euros-del-fondo-internacional-keystone-para-crear-una-de-las-mayores-redes-de-recarga-de-vehiculos-electricos-en-espana\\\/\",\"name\":\"Eranovum obtiene 26,5 millones de euros del fondo internacional Keystone para crear una de las mayores redes de recarga de veh\u00edculos el\u00e9ctricos en Espa\u00f1a - Eranovum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eranovum.energy\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eranovum.energy\\\/es\\\/sala-de-prensa\\\/eranovum-obtiene-265-millones-de-euros-del-fondo-internacional-keystone-para-crear-una-de-las-mayores-redes-de-recarga-de-vehiculos-electricos-en-espana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eranovum.energy\\\/es\\\/sala-de-prensa\\\/eranovum-obtiene-265-millones-de-euros-del-fondo-internacional-keystone-para-crear-una-de-las-mayores-redes-de-recarga-de-vehiculos-electricos-en-espana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eranovum.energy\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/eranovum-ev-charge.jpg\",\"datePublished\":\"2022-06-15T07:38:56+00:00\",\"dateModified\":\"2022-06-15T18:18:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eranovum.energy\\\/es\\\/sala-de-prensa\\\/eranovum-obtiene-265-millones-de-euros-del-fondo-internacional-keystone-para-crear-una-de-las-mayores-redes-de-recarga-de-vehiculos-electricos-en-espana\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eranovum.energy\\\/es\\\/sala-de-prensa\\\/eranovum-obtiene-265-millones-de-euros-del-fondo-internacional-keystone-para-crear-una-de-las-mayores-redes-de-recarga-de-vehiculos-electricos-en-espana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/eranovum.energy\\\/es\\\/sala-de-prensa\\\/eranovum-obtiene-265-millones-de-euros-del-fondo-internacional-keystone-para-crear-una-de-las-mayores-redes-de-recarga-de-vehiculos-electricos-en-espana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eranovum.energy\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/eranovum-ev-charge.jpg\",\"contentUrl\":\"https:\\\/\\\/eranovum.energy\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/eranovum-ev-charge.jpg\",\"width\":2372,\"height\":1578},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eranovum.energy\\\/es\\\/sala-de-prensa\\\/eranovum-obtiene-265-millones-de-euros-del-fondo-internacional-keystone-para-crear-una-de-las-mayores-redes-de-recarga-de-vehiculos-electricos-en-espana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eranovum.energy\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eranovum obtiene 26,5 millones de euros del fondo internacional Keystone para crear una de las mayores redes de recarga de veh\u00edculos el\u00e9ctricos en Espa\u00f1a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eranovum.energy\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/eranovum.energy\\\/es\\\/\",\"name\":\"Eranovum\",\"description\":\"Leading the new era of energy\",\"publisher\":{\"@id\":\"https:\\\/\\\/eranovum.energy\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eranovum.energy\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eranovum.energy\\\/es\\\/#organization\",\"name\":\"Eranovum\",\"url\":\"https:\\\/\\\/eranovum.energy\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/eranovum.energy\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eranovum.energy\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/cropped-eranovum-logo-web.png\",\"contentUrl\":\"https:\\\/\\\/eranovum.energy\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/cropped-eranovum-logo-web.png\",\"width\":351,\"height\":41,\"caption\":\"Eranovum\"},\"image\":{\"@id\":\"https:\\\/\\\/eranovum.energy\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eranovum.energy\\\/es\\\/#\\\/schema\\\/person\\\/8899ee21829052240fb60fc9ce870a50\",\"name\":\"quadrosphera\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bfa148e4674c11710ff73f8c29dc349dc77f5bc8cdcc356e0f0ea4497d2083df?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bfa148e4674c11710ff73f8c29dc349dc77f5bc8cdcc356e0f0ea4497d2083df?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bfa148e4674c11710ff73f8c29dc349dc77f5bc8cdcc356e0f0ea4497d2083df?s=96&d=mm&r=g\",\"caption\":\"quadrosphera\"},\"sameAs\":[\"https:\\\/\\\/eranovum.energy\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eranovum obtiene 26,5 millones de euros del fondo internacional Keystone para crear una de las mayores redes de recarga de veh\u00edculos el\u00e9ctricos en Espa\u00f1a - Eranovum","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eranovum.energy\/es\/sala-de-prensa\/eranovum-obtiene-265-millones-de-euros-del-fondo-internacional-keystone-para-crear-una-de-las-mayores-redes-de-recarga-de-vehiculos-electricos-en-espana\/","og_locale":"es_ES","og_type":"article","og_title":"Eranovum obtiene 26,5 millones de euros del fondo internacional Keystone para crear una de las mayores redes de recarga de veh\u00edculos el\u00e9ctricos en Espa\u00f1a - Eranovum","og_description":"Toda la red de Eranovum suministrar\u00e1 energ\u00eda 100% renovable Hasta la fecha, la red de&hellip;","og_url":"https:\/\/eranovum.energy\/es\/sala-de-prensa\/eranovum-obtiene-265-millones-de-euros-del-fondo-internacional-keystone-para-crear-una-de-las-mayores-redes-de-recarga-de-vehiculos-electricos-en-espana\/","og_site_name":"Eranovum","article_published_time":"2022-06-15T07:38:56+00:00","article_modified_time":"2022-06-15T18:18:00+00:00","og_image":[{"width":2372,"height":1578,"url":"https:\/\/eranovum.energy\/wp-content\/uploads\/2022\/09\/eranovum-ev-charge.jpg","type":"image\/jpeg"}],"author":"quadrosphera","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"quadrosphera","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eranovum.energy\/es\/sala-de-prensa\/eranovum-obtiene-265-millones-de-euros-del-fondo-internacional-keystone-para-crear-una-de-las-mayores-redes-de-recarga-de-vehiculos-electricos-en-espana\/#article","isPartOf":{"@id":"https:\/\/eranovum.energy\/es\/sala-de-prensa\/eranovum-obtiene-265-millones-de-euros-del-fondo-internacional-keystone-para-crear-una-de-las-mayores-redes-de-recarga-de-vehiculos-electricos-en-espana\/"},"author":{"name":"quadrosphera","@id":"https:\/\/eranovum.energy\/es\/#\/schema\/person\/8899ee21829052240fb60fc9ce870a50"},"headline":"Eranovum obtiene 26,5 millones de euros del fondo internacional Keystone para crear una de las mayores redes de recarga de veh\u00edculos el\u00e9ctricos en Espa\u00f1a","datePublished":"2022-06-15T07:38:56+00:00","dateModified":"2022-06-15T18:18:00+00:00","mainEntityOfPage":{"@id":"https:\/\/eranovum.energy\/es\/sala-de-prensa\/eranovum-obtiene-265-millones-de-euros-del-fondo-internacional-keystone-para-crear-una-de-las-mayores-redes-de-recarga-de-vehiculos-electricos-en-espana\/"},"wordCount":846,"publisher":{"@id":"https:\/\/eranovum.energy\/es\/#organization"},"image":{"@id":"https:\/\/eranovum.energy\/es\/sala-de-prensa\/eranovum-obtiene-265-millones-de-euros-del-fondo-internacional-keystone-para-crear-una-de-las-mayores-redes-de-recarga-de-vehiculos-electricos-en-espana\/#primaryimage"},"thumbnailUrl":"https:\/\/eranovum.energy\/wp-content\/uploads\/2022\/09\/eranovum-ev-charge.jpg","keywords":["E-mobility","Veh\u00edculos el\u00e9ctricos","Ev"],"articleSection":["Sala de Prensa"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/eranovum.energy\/es\/sala-de-prensa\/eranovum-obtiene-265-millones-de-euros-del-fondo-internacional-keystone-para-crear-una-de-las-mayores-redes-de-recarga-de-vehiculos-electricos-en-espana\/","url":"https:\/\/eranovum.energy\/es\/sala-de-prensa\/eranovum-obtiene-265-millones-de-euros-del-fondo-internacional-keystone-para-crear-una-de-las-mayores-redes-de-recarga-de-vehiculos-electricos-en-espana\/","name":"Eranovum obtiene 26,5 millones de euros del fondo internacional Keystone para crear una de las mayores redes de recarga de veh\u00edculos el\u00e9ctricos en Espa\u00f1a - Eranovum","isPartOf":{"@id":"https:\/\/eranovum.energy\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eranovum.energy\/es\/sala-de-prensa\/eranovum-obtiene-265-millones-de-euros-del-fondo-internacional-keystone-para-crear-una-de-las-mayores-redes-de-recarga-de-vehiculos-electricos-en-espana\/#primaryimage"},"image":{"@id":"https:\/\/eranovum.energy\/es\/sala-de-prensa\/eranovum-obtiene-265-millones-de-euros-del-fondo-internacional-keystone-para-crear-una-de-las-mayores-redes-de-recarga-de-vehiculos-electricos-en-espana\/#primaryimage"},"thumbnailUrl":"https:\/\/eranovum.energy\/wp-content\/uploads\/2022\/09\/eranovum-ev-charge.jpg","datePublished":"2022-06-15T07:38:56+00:00","dateModified":"2022-06-15T18:18:00+00:00","breadcrumb":{"@id":"https:\/\/eranovum.energy\/es\/sala-de-prensa\/eranovum-obtiene-265-millones-de-euros-del-fondo-internacional-keystone-para-crear-una-de-las-mayores-redes-de-recarga-de-vehiculos-electricos-en-espana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eranovum.energy\/es\/sala-de-prensa\/eranovum-obtiene-265-millones-de-euros-del-fondo-internacional-keystone-para-crear-una-de-las-mayores-redes-de-recarga-de-vehiculos-electricos-en-espana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eranovum.energy\/es\/sala-de-prensa\/eranovum-obtiene-265-millones-de-euros-del-fondo-internacional-keystone-para-crear-una-de-las-mayores-redes-de-recarga-de-vehiculos-electricos-en-espana\/#primaryimage","url":"https:\/\/eranovum.energy\/wp-content\/uploads\/2022\/09\/eranovum-ev-charge.jpg","contentUrl":"https:\/\/eranovum.energy\/wp-content\/uploads\/2022\/09\/eranovum-ev-charge.jpg","width":2372,"height":1578},{"@type":"BreadcrumbList","@id":"https:\/\/eranovum.energy\/es\/sala-de-prensa\/eranovum-obtiene-265-millones-de-euros-del-fondo-internacional-keystone-para-crear-una-de-las-mayores-redes-de-recarga-de-vehiculos-electricos-en-espana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eranovum.energy\/es\/"},{"@type":"ListItem","position":2,"name":"Eranovum obtiene 26,5 millones de euros del fondo internacional Keystone para crear una de las mayores redes de recarga de veh\u00edculos el\u00e9ctricos en Espa\u00f1a"}]},{"@type":"WebSite","@id":"https:\/\/eranovum.energy\/es\/#website","url":"https:\/\/eranovum.energy\/es\/","name":"Eranovum","description":"Leading the new era of energy","publisher":{"@id":"https:\/\/eranovum.energy\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eranovum.energy\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/eranovum.energy\/es\/#organization","name":"Eranovum","url":"https:\/\/eranovum.energy\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eranovum.energy\/es\/#\/schema\/logo\/image\/","url":"https:\/\/eranovum.energy\/wp-content\/uploads\/2022\/04\/cropped-eranovum-logo-web.png","contentUrl":"https:\/\/eranovum.energy\/wp-content\/uploads\/2022\/04\/cropped-eranovum-logo-web.png","width":351,"height":41,"caption":"Eranovum"},"image":{"@id":"https:\/\/eranovum.energy\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/eranovum.energy\/es\/#\/schema\/person\/8899ee21829052240fb60fc9ce870a50","name":"quadrosphera","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bfa148e4674c11710ff73f8c29dc349dc77f5bc8cdcc356e0f0ea4497d2083df?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bfa148e4674c11710ff73f8c29dc349dc77f5bc8cdcc356e0f0ea4497d2083df?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bfa148e4674c11710ff73f8c29dc349dc77f5bc8cdcc356e0f0ea4497d2083df?s=96&d=mm&r=g","caption":"quadrosphera"},"sameAs":["https:\/\/eranovum.energy"]}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/eranovum.energy\/es\/wp-json\/wp\/v2\/posts\/2084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eranovum.energy\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eranovum.energy\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eranovum.energy\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eranovum.energy\/es\/wp-json\/wp\/v2\/comments?post=2084"}],"version-history":[{"count":0,"href":"https:\/\/eranovum.energy\/es\/wp-json\/wp\/v2\/posts\/2084\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eranovum.energy\/es\/wp-json\/wp\/v2\/media\/2077"}],"wp:attachment":[{"href":"https:\/\/eranovum.energy\/es\/wp-json\/wp\/v2\/media?parent=2084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eranovum.energy\/es\/wp-json\/wp\/v2\/categories?post=2084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eranovum.energy\/es\/wp-json\/wp\/v2\/tags?post=2084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}